{"id":9550,"date":"2026-02-11T16:11:41","date_gmt":"2026-02-11T15:11:41","guid":{"rendered":"https:\/\/www.casadeljazz.com\/?post_type=evento&#038;p=9550"},"modified":"2026-04-20T16:37:14","modified_gmt":"2026-04-20T14:37:14","slug":"9550","status":"publish","type":"evento","link":"https:\/\/www.casadeljazz.com\/en\/evento\/9550\/","title":{"rendered":"Junctions Beyond Jazz: Lyrica"},"content":{"rendered":"<p><em><strong>Lyrica<\/strong><\/em>: un lavoro introspettivo per voce, contrabbasso, chitarra classica, organo bina, nastro magnetico e percussioni, che fonde\u00a0 poesia e\u00a0 musica nell&#8217;eco della Lirica come forma di poesia accompagnata. Ispirato alle linee e alle forme di Kandinsky, verr\u00e0 presentato dal suo autore, <strong>Massimo Ceccarelli<\/strong>\u00a0con <strong>Pietro Pompei<\/strong> alle percussioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lyrica: un lavoro introspettivo per voce, contrabbasso, chitarra classica, organo bina, nastro magnetico e percussioni, che fonde\u00a0 poesia e\u00a0 musica nell&#8217;eco della Lirica come forma di poesia accompagnata. Ispirato alle linee e alle forme di Kandinsky, verr\u00e0 presentato dal suo autore, Massimo Ceccarelli\u00a0con Pietro Pompei alle percussioni.<\/p>\n","protected":false},"featured_media":10631,"template":"","categoria-evento":[118],"tag-evento":[],"class_list":["post-9550","evento","type-evento","status-publish","has-post-thumbnail","hentry","categoria-evento-concerti"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/evento\/9550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/types\/evento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/media\/10631"}],"wp:attachment":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/media?parent=9550"}],"wp:term":[{"taxonomy":"categoria-evento","embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/categoria-evento?post=9550"},{"taxonomy":"tag-evento","embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/tag-evento?post=9550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}