{"id":6407,"date":"2025-02-06T11:02:10","date_gmt":"2025-02-06T10:02:10","guid":{"rendered":"https:\/\/www.casadeljazz.com\/?post_type=evento&#038;p=6407"},"modified":"2025-02-06T11:02:10","modified_gmt":"2025-02-06T10:02:10","slug":"giovanni-guidi-feat-james-brandon-lewis-a-new-day","status":"publish","type":"evento","link":"https:\/\/www.casadeljazz.com\/en\/evento\/giovanni-guidi-feat-james-brandon-lewis-a-new-day\/","title":{"rendered":"Giovanni Guidi feat. James Brandon\u00a0Lewis \u2013 &#8220;A New Day&#8221;"},"content":{"rendered":"<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div data-olk-copy-source=\"MessageBody\">Ravvivando l&#8217;interplay familiare e fluido con i compagni di viaggio <strong>Joe Rehmer<\/strong> e<strong> Jo\u00e3o Lobo<\/strong> \u2013 la collaborazione musicale del trio nasce ormai oltre un decennio fa \u2013 in &#8220;A New Day&#8221; il pianista italiano <strong>Giovanni <span class=\"x_gmail-il\">Guidi<\/span><\/strong>amplia la gamma strumentale del gruppo con l&#8217;introduzione del sassofonista americano <strong>James Brandon\u00a0<span class=\"x_gmail-il\">Lewis<\/span><\/strong>, che in questo album fa il suo debutto con ECM. Non solo l&#8217;orizzonte dell&#8217;ensemble si amplia; con l&#8217;aggiunta di <strong>Brandon\u00a0<span class=\"x_gmail-il\">Lewis<\/span><\/strong>, si esplorano nuovi idiomi e prospettive, e si intraprendono percorsi strumentali diversi, ispirati da un accresciuto senso di comunicazione complessiva e dal tono inconfondibile e sicuro di\u00a0<strong><span class=\"x_gmail-il\">Lewis<\/span><\/strong>. Registrato nell&#8217;agosto 2023 agli Studios La Buissonne nel sud della Francia, l&#8217;album \u00e8 stato prodotto da <strong>Manfred Eicher<\/strong>.<\/div>\n<p>&nbsp;<\/p>\n<div data-olk-copy-source=\"MessageBody\"><strong>Formazione<\/strong><br \/>\nGiovanni Guidi \u2013 Pianoforte<br \/>\nJames Brandon Lewis \u2013 Sax tenore<br \/>\nJoe Rehmer \u2013 Contrabbasso<br \/>\nJoao Lobo \u2013 Batteria<\/div>\n<\/div>\n<\/div>\n<div data-olk-copy-source=\"MessageBody\"><\/div>\n<div data-olk-copy-source=\"MessageBody\">\n<p>Foto \u00a9 Sam Harfouche \/ ECM Records<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ravvivando l&#8217;interplay familiare e fluido con i compagni di viaggio Joe Rehmer e Jo\u00e3o Lobo \u2013 la collaborazione musicale del trio nasce ormai oltre un decennio fa \u2013 in &#8220;A New Day&#8221; il pianista italiano Giovanni Guidiamplia la gamma strumentale del gruppo con l&#8217;introduzione del sassofonista americano James Brandon\u00a0Lewis, che in questo album fa il<a class=\"excerpt-read-more\" href=\"https:\/\/www.casadeljazz.com\/en\/evento\/giovanni-guidi-feat-james-brandon-lewis-a-new-day\/\" title=\"ReadGiovanni Guidi feat. James Brandon\u00a0Lewis \u2013 &#8220;A New Day&#8221;\">&#8230; Read more &raquo;<\/a><\/p>\n","protected":false},"featured_media":6408,"template":"","categoria-evento":[118],"tag-evento":[],"class_list":["post-6407","evento","type-evento","status-publish","has-post-thumbnail","hentry","categoria-evento-concerti"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/evento\/6407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/types\/evento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/media\/6408"}],"wp:attachment":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/media?parent=6407"}],"wp:term":[{"taxonomy":"categoria-evento","embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/categoria-evento?post=6407"},{"taxonomy":"tag-evento","embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/tag-evento?post=6407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}