{"id":4747,"date":"2024-03-27T15:08:27","date_gmt":"2024-03-27T14:08:27","guid":{"rendered":"https:\/\/www.casadeljazz.com\/evento\/b-i-t-duo\/"},"modified":"2024-07-30T03:25:41","modified_gmt":"2024-07-30T01:25:41","slug":"b-i-t-duo","status":"publish","type":"evento","link":"https:\/\/www.casadeljazz.com\/en\/evento\/b-i-t-duo\/","title":{"rendered":"B.I.T. duo"},"content":{"rendered":"\n<p class=\"has-text-align-center\">Manuela Pasqui piano<\/p>\n\n\n\n<p class=\"has-text-align-center\">Danielle Di Majo sax alto e soprano<\/p>\n\n\n\n<p class=\"has-text-align-center\">Special guest<\/p>\n\n\n\n<p class=\"has-text-align-center\">Antonella Vitale voce<\/p>\n\n\n\n<p class=\"has-text-align-center\">Giancarlo Maurino sax tenore<\/p>\n\n\n\n<p class=\"has-text-align-center\">Giampiero Silvestri batteria<\/p>\n\n\n\n<p>Danielle e Manuela lavorano sul duo da circa quattro anni\u00a0in\u00a0grande sintonia,\u00a0conuna condivisione di obiettivi artistici, che ha dato la scintilla al loro \u201cricercare\u201d. Il loro\u00a0lavoro \u00e8 frutto di una continua e profonda ricerca che fonde studio compositivo e improvvisazione cercando di\u00a0trovare l\u2019equilibrio tra molti elementi in gioco, mo(vi)mento dopo mo(vi)mento, istante dopo istante. Nel corso del concerto verr\u00e0 presentato anche il nuovo progetto \u201cPuccini my love&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manuela Pasqui piano Danielle Di Majo sax alto e soprano Special guest Antonella Vitale voce Giancarlo Maurino sax tenore Giampiero Silvestri batteria Danielle e Manuela lavorano sul duo da circa quattro anni\u00a0in\u00a0grande sintonia,\u00a0conuna condivisione di obiettivi artistici, che ha dato la scintilla al loro \u201cricercare\u201d. Il loro\u00a0lavoro \u00e8 frutto di una continua e profonda ricerca<a class=\"excerpt-read-more\" href=\"https:\/\/www.casadeljazz.com\/en\/evento\/b-i-t-duo\/\" title=\"ReadB.I.T. duo\">&#8230; Read more &raquo;<\/a><\/p>\n","protected":false},"featured_media":1031,"template":"","categoria-evento":[118],"tag-evento":[99],"class_list":["post-4747","evento","type-evento","status-publish","has-post-thumbnail","hentry","categoria-evento-concerti","tag-evento-concerti"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/evento\/4747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/types\/evento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/media\/1031"}],"wp:attachment":[{"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/media?parent=4747"}],"wp:term":[{"taxonomy":"categoria-evento","embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/categoria-evento?post=4747"},{"taxonomy":"tag-evento","embeddable":true,"href":"https:\/\/www.casadeljazz.com\/en\/wp-json\/wp\/v2\/tag-evento?post=4747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}